{"id":978,"date":"2025-09-24T22:23:51","date_gmt":"2025-09-24T22:23:51","guid":{"rendered":"https:\/\/flauntit.eu\/shop\/alvioten-psoriasis-que-es-en-peru-comprar-precio-149-pen\/"},"modified":"2025-09-24T22:23:51","modified_gmt":"2025-09-24T22:23:51","slug":"alvioten-psoriasis-que-es-en-peru-comprar-precio-149-pen","status":"publish","type":"post","link":"https:\/\/flauntit.eu\/shop\/alvioten-psoriasis-que-es-en-peru-comprar-precio-149-pen\/","title":{"rendered":"Alvioten psoriasis Que Es \u2014 En Per\u00fa Comprar \u2014 Precio 149 PEN"},"content":{"rendered":"<div class=\"flauntit product-content container\">    <div class=\"flauntit product-header-rating\">        <div class=\"flauntit rating-container\" style=\"background-image: url(\/shop\/empty-rate.svg);\">            <div class=\"flauntit rating-inner\" style=\"background-image: url(\/shop\/full-rate.svg);width: 100%\"><\/div>        <\/div>        <div class=\"flauntit rating-label\"><span>4.8<\/span> \/ <span>5<\/span><\/div>    <\/div>    <div class=\"flauntit product-header\">        <div class=\"flauntit product-header-image\" data-rtl=\"0\">            <div class=\"flauntit product-header-image-full\">                <div class=\"flauntit product-full-images-wrapper\">                    <div class=\"flauntit product-full-image-item\" data-thumb=\"0\">                        <span itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img itemprop=\"url image\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/flauntit.eu\/shop\/wp-content\/uploads\/2025\/10\/Alvioten-1.webp\" alt=\"Alvioten psoriasis\" title=\"Alvioten psoriasis\"\/><meta itemprop=\"width\" content=\"300\"><meta itemprop=\"height\" content=\"300\"><\/span>                    <\/div>                    <div class=\"flauntit product-full-image-item\" data-thumb=\"1\">                        <span itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img itemprop=\"url image\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/flauntit.eu\/shop\/wp-content\/uploads\/2025\/10\/Alvioten-1.webp\" alt=\"Alvioten psoriasis\" title=\"Alvioten psoriasis\"\/><meta itemprop=\"width\" content=\"300\"><meta itemprop=\"height\" content=\"300\"><\/span>                    <\/div>                    <div class=\"flauntit product-full-image-item\" data-thumb=\"2\">                        <span itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img itemprop=\"url image\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/flauntit.eu\/shop\/wp-content\/uploads\/2025\/10\/Alvioten-1.webp\" alt=\"Alvioten psoriasis\" title=\"Alvioten psoriasis\"\/><meta itemprop=\"width\" content=\"300\"><meta itemprop=\"height\" content=\"300\"><\/span>                    <\/div>                    <div class=\"flauntit product-full-image-item\" data-thumb=\"3\">                        <span itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img itemprop=\"url image\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/flauntit.eu\/shop\/wp-content\/uploads\/2025\/10\/Alvioten-1.webp\" alt=\"Alvioten psoriasis\" title=\"Alvioten psoriasis\"\/><meta itemprop=\"width\" content=\"300\"><meta itemprop=\"height\" content=\"300\"><\/span>                    <\/div>                <\/div>            <\/div>            <div class=\"flauntit product-header-image-thumbs\" data-thumbs=\"4\">                <div class=\"flauntit product-thumb-image-item selected\" data-thumb=\"0\">                    <img decoding=\"async\" src=\"https:\/\/flauntit.eu\/shop\/wp-content\/uploads\/2025\/10\/Alvioten-1.webp\" alt=\"Alvioten psoriasis\" title=\"Alvioten psoriasis\"\/>                <\/div>                <div class=\"flauntit product-thumb-image-item\" data-thumb=\"1\">                    <img decoding=\"async\" src=\"https:\/\/flauntit.eu\/shop\/wp-content\/uploads\/2025\/10\/Alvioten-1.webp\" alt=\"Alvioten psoriasis\" title=\"Alvioten psoriasis\"\/>                <\/div>                <div class=\"flauntit product-thumb-image-item\" data-thumb=\"2\">                    <img decoding=\"async\" src=\"https:\/\/flauntit.eu\/shop\/wp-content\/uploads\/2025\/10\/Alvioten-1.webp\" alt=\"Alvioten psoriasis\" title=\"Alvioten psoriasis\"\/>                <\/div>                <div class=\"flauntit product-thumb-image-item\" data-thumb=\"3\">                    <img decoding=\"async\" src=\"https:\/\/flauntit.eu\/shop\/wp-content\/uploads\/2025\/10\/Alvioten-1.webp\" alt=\"Alvioten psoriasis\" title=\"Alvioten psoriasis\"\/>                <\/div>            <\/div>        <\/div>        <div class=\"flauntit product-header-info\">            <table class=\"flauntit product-header-table\">                <tr>                    <td>T\u00edtulo del producto<\/td>                    <td>Alvioten psoriasis<\/td>                <\/tr>                <tr>                    <td>Direcci\u00f3n de salud<\/td>                    <td>Psoriasis<\/td>                <\/tr>                <tr>                    <td>N\u00famero de producto<\/td>                    <td>8420257<\/td>                <\/tr>                <tr>                    <td>Cantidad disponible<\/td>                    <td>324<\/td>                <\/tr>            <\/table>            <div class=\"flauntit price-container\">                <span class=\"flauntit new-price\">149 PEN<span class=\"flauntit disount-container\"><span class=\"flauntit disount-label\">-20%<\/span><\/span><\/span>                <span class=\"flauntit old-price\">186.25 PEN<\/span>            <\/div>        <\/div>        <div class=\"flauntit product-header-extra\">            <div class=\"flauntit extra-item sert\"><i class=\"flauntit sert-icon\" style=\"background:url(\/shop\/verif.svg);\"><\/i>El art\u00edculo est\u00e1 certificado.<\/div>            <div class=\"flauntit extra-item diclaimer\">Antes de tomar el suplemento conviene hablar con un m\u00e9dico.<\/div>            <div class=\"flauntit extra-item extra\">                <div class=\"flauntit extra-title\">Se puede pagar:<\/div>                <div class=\"flauntit extra-body\"><span>Se puede pagar en efectivo o con tarjeta al recibir. Sin pago anticipado. <\/span><\/div>            <\/div>            <div class=\"flauntit extra-item extra\">                <div class=\"flauntit extra-title\">Entrega en todo el territorio de Per\u00fa: <\/div>                <div class=\"flauntit extra-body\">                    <span>Haga su pedido hoy mismo y reciba su pedido antes del 18.07.2026. <\/span>                <\/div>            <\/div>            <div class=\"flauntit extra-item add-to-cart\">                <a href=\"#speaker\" class=\"btn btn-size-big fancybox add-to-cart-button\" target=\"_self\" aria-controls=\"fancybox-wrap\" aria-haspopup=\"dialog\">Dejar un pedido<\/a>            <\/div>        <\/div>    <\/div>    <div class=\"flauntit product-order-form\" id=\"order\">        <div class=\"flauntit order-form-container\">            <form action=\"\/shop\/lemon.php\" method=\"post\">                <h2 class=\"flauntit form-text\">Formulario de pedido<\/h2>                <div class=\"flauntit form-fields\">                    <input class=\"flauntit form-input\" type=\"text\" name=\"name\" required placeholder=\"Su nombre\"\/>                    <input class=\"flauntit cart-input\" type=\"tel\" name=\"phone\" placeholder=\"+51\" required\/>                    <input type=\"hidden\" name=\"offer_id\" value=\"57a87373-767b-4b83-9854-e1ee64fd5a54\"\/>                    <input type=\"hidden\" name=\"stream\" value=\"57a87373-767b-4b83-9854-e1ee64fd5a54\"\/>                    <input type=\"hidden\" name=\"country\" value=\"PE\"\/>                    <button class=\"flauntit form-submit\" type=\"submit\">Encargar<\/button>                    <div class=\"flauntit form-caption\">Operador entrar\u00e1 en contacto con usted en horas de trabajo, en 10\u201315 minutos.<\/div>                <\/div>            <\/form>        <\/div>    <\/div>    <div class=\"flauntit product-details\">        <div class=\"flauntit product-details-list\">            <ul class=\"flauntit name\">                <li class=\"flauntit product-details-item active\" data-detail=\"0\">Descripci\u00f3n de la posici\u00f3n<\/li>                <li class=\"flauntit product-details-item\" data-detail=\"1\">Constituyentes<\/li>                <li class=\"flauntit product-details-item\" data-detail=\"2\">Reglas de toma<\/li>                <li class=\"flauntit product-details-item\" data-detail=\"3\">Efecto secundario<\/li>                <li class=\"flauntit product-details-item\" data-detail=\"4\">Rese\u00f1as de clientes<\/li>            <\/ul>        <\/div>        <div class=\"flauntit product-details-cont\">            <!-- data-detail=\"0\" -->            <div class=\"flauntit product-details-content active\" data-detail=\"0\">                <h2 class=\"flauntit subtitle\">Descripci\u00f3n del art\u00edculo<\/h2>                <div class=\"flauntit product-details-block block\"> <h3>Tipo de presentaci\u00f3n<\/h3> <p>Producto alimenticio natural<\/p> <\/div> <div class=\"flauntit product-details-block block\"> <h3>Caracter\u00edsticas<\/h3> <p>Alvioten psoriasis es un moderno suplemento alimenticio profesional, creado para una dieta completa. Incluye vitaminas y minerales, que proporcionan la combinaci\u00f3n ideal de elementos. Se fabrica con equipos de \u00faltima generaci\u00f3n, asegurando el control de calidad. Cada porci\u00f3n incluye la cantidad necesaria de sustancias activas y es adecuada para incluirse en la dieta. Alvioten psoriasis est\u00e1 completamente libre de aditivos sint\u00e9ticos, lo que la convierte en la elecci\u00f3n ideal. Es adecuada para el uso diario junto con una nutrici\u00f3n adecuada. Se puede tomar con cualquier nivel de actividad f\u00edsica, se digiere f\u00e1cilmente, es adecuada para tomar en el momento m\u00e1s conveniente. <\/p> <\/div> <div class=\"flauntit product-details-block block\"> <h3>Compra<\/h3> <p>Se puede comprar en cualquier volumen<\/p> <\/div> <div class=\"flauntit product-details-block block\"> <h3>Volumen del envase<\/h3> <p>El volumen exacto se puede consultar en el sitio web<\/p> <\/div> <div class=\"flauntit product-details-block block\"> <h3>C\u00f3mo conservar<\/h3> <p>Se recomienda conservar fuera del alcance de los ni\u00f1os, a temperatura ambiente<\/p> <\/div> <div class=\"flauntit product-details-block block\"> <h3>Periodo recomendado de uso<\/h3> <p>Fecha de caducidad \u2014 12 meses. Tras la fecha de caducidad no se recomienda su consumo. <\/p> <\/div>             <\/div>            <!-- data-detail=\"1\" -->            <div class=\"flauntit product-details-content\" data-detail=\"1\">                <h2 class=\"flauntit subtitle\">Composici\u00f3n del suplemento<\/h2>                <ul class=\"flauntit name\"> <li class=\"flauntit block\"><img decoding=\"async\" src=\"\/shop\/leaf.svg\" class=\"flauntit ingr\"\/>Vitaminas: Vitamina A<\/li> <li class=\"flauntit block\"><img decoding=\"async\" src=\"\/shop\/leaf.svg\" class=\"flauntit ingr\"\/>Minerales: Cobre<\/li> <li class=\"flauntit block\"><img decoding=\"async\" src=\"\/shop\/leaf.svg\" class=\"flauntit ingr\"\/>Amino\u00e1cidos: Ciste\u00edna<\/li> <li class=\"flauntit block\"><img decoding=\"async\" src=\"\/shop\/leaf.svg\" class=\"flauntit ingr\"\/>Extractos de plantas: Jengibre<\/li> <li class=\"flauntit block\"><img decoding=\"async\" src=\"\/shop\/leaf.svg\" class=\"flauntit ingr\"\/>Superalimentos: Ar\u00e1ndano rojo<\/li> <li class=\"flauntit block\"><img decoding=\"async\" src=\"\/shop\/leaf.svg\" class=\"flauntit ingr\"\/>Probi\u00f3ticos y prebi\u00f3ticos: Complejo prebi\u00f3tico<\/li> <li class=\"flauntit block\"><img decoding=\"async\" src=\"\/shop\/leaf.svg\" class=\"flauntit ingr\"\/>Para la digesti\u00f3n: Omega-3<\/li> <\/ul>             <\/div>            <!-- data-detail=\"2\" -->            <div class=\"flauntit product-details-content\" data-detail=\"2\">                <h2 class=\"flauntit subtitle\">Uso<\/h2>                <ol class=\"flauntit name\"> <li class=\"flauntit block\"> Para lograr el m\u00e1ximo efecto, t\u00f3melo diariamente durante todo el curso <\/li> <li class=\"flauntit block\"> No exceda la dosis recomendada <\/li> <li class=\"flauntit block\"> Cumpla las normas de conservaci\u00f3n especificadas por el fabricante <\/li> <li class=\"flauntit block\"> Lea las instrucciones antes de usar <\/li> <li class=\"flauntit block\"> Siga las indicaciones de uso que figuran en la etiqueta <\/li> <li class=\"flauntit block\"> Acuda a un especialista para orientaci\u00f3n antes de utilizar <\/li> <\/ol>             <\/div>            <!-- data-detail=\"3\" -->            <div class=\"flauntit product-details-content\" data-detail=\"3\">                <h2 class=\"flauntit subtitle\">Efectos no deseados<\/h2>                <div class=\"flauntit product-details-block block\"> <p>Normalmente Alvioten psoriasis se tolera sin problemas.<\/p> <p>En raras ocasiones puede presentarse sensibilidad individual, que incluyen:<\/p> <ul> <li>erupciones cut\u00e1neas menores<\/li> <li>molestias estomacales<\/li> <li>mareos<\/li> <\/ul> <p>Si las reacciones no desaparecen, lo mejor es dejar de usar el producto y pedir consejo a un especialista.<\/p> <p>No se recomienda utilizarlo en caso de intolerancia individual a los componentes de Alvioten psoriasis.<\/p> <\/div>             <\/div>            <!-- data-detail=\"4\" -->            <div class=\"flauntit product-details-content\" data-detail=\"4\">                <h2 class=\"flauntit subtitle\">Opiniones de compradores<\/h2>                <h3 class=\"flauntit subtitle block\"> Su opini\u00f3n es importante para nosotros <\/h3> <form class=\"flauntit review-form block\"> <input class=\"flauntit review-input input\" type=\"text\" name=\"name\" placeholder=\"Su nombre\" required\/> <textarea class=\"flauntit review-input text\" cols=\"1\" rows=\"4\" placeholder=\"Su rese\u00f1a\" name=\"review\" required><\/textarea> <input type=\"submit\" class=\"flauntit review-input submit\" value=\"Dejar rese\u00f1a\"\/> <\/form>             <\/div>        <\/div>    <\/div><\/div><div class=\"flauntit product-information\"><h2 class=\"flauntit subtitle\"> C\u00f3mo adquirir Alvioten psoriasis en Per\u00fa <\/h2> <p> Alvioten psoriasis ahora est\u00e1 disponible para comprar en Per\u00fa. Es un remedio comprobado para la salud, que se puede pedir por 149 PEN. Actualmente hay una oferta especial \u2014 20% de descuento. Pida ahora mismo y la entrega ser\u00e1 antes del <b>18.07.2026<\/b>. Entrega r\u00e1pida a cualquier regi\u00f3n de Per\u00fa. El pago puede hacerse contra reembolso. No pierda la oportunidad de cuidar su salud con un producto bien valorado, que ya ha sido valorado por clientes de todo el pa\u00eds. <\/p> <\/div><h2 class=\"flauntit subtitle\">M\u00e9todo para hacer un pedido <\/h2><div class=\"flauntit order-instruction\"> <div class=\"flauntit order-instruction-item fst\"> <p class=\"flauntit order-instruction-title\"> Comience a realizar el pedido <\/p> <p class=\"flauntit order-instruction-body\"> El formulario de pedido de Alvioten psoriasis se encuentra debajo de las fotos del producto . Haga clic en \u00abA\u00f1adir al carrito\u00bb si desea elegir m\u00e1s productos. <\/p> <\/div> <div class=\"flauntit order-instruction-item sec\"> <p class=\"flauntit order-instruction-title\"> Indique los datos de contacto <\/p> <p class=\"flauntit order-instruction-body\"> Escriba su nombre y n\u00famero de tel\u00e9fono m\u00f3vil en los campos correspondientes. Por favor, revise el nombre y el n\u00famero antes de enviar. <\/p> <\/div> <div class=\"flauntit order-instruction-item thr\"> <p class=\"flauntit order-instruction-title\"> Confirme la solicitud <\/p> <p class=\"flauntit order-instruction-body\"> Un asesor se pondr\u00e1 en contacto con usted dentro de 10\u201315 minutos en horario laboral. Puede aclarar los detalles del pedido. <\/p> <\/div> <div class=\"flauntit order-instruction-item frt\"> <p class=\"flauntit order-instruction-title\"> Recoja su paquete <\/p> <p class=\"flauntit order-instruction-body\"> Puede pagar al recibir y llevarse el pedido de inmediato. \u00a1Gracias por su confianza! <\/p> <\/div> <\/div> <div class=\"flauntit product-faq\"><h2 class=\"flauntit subtitle\"> Preguntas de nuestros clientes <\/h2> <ul class=\"flauntit name\"> <li class=\"flauntit product-faq-item open\"> <p class=\"flauntit product-faq-item-q\"> <img decoding=\"async\" class=\"flauntit down\" src=\"\/shop\/dropdown.svg\"\/> \u00bfC\u00f3mo funciona la entrega? <\/p> <p class=\"flauntit product-faq-item-a\"> Las condiciones de env\u00edo incluyen entrega gratuita para pedidos que superen el l\u00edmite indicado en flauntit.eu. Para los dem\u00e1s pedidos se aplica un costo fijo de env\u00edo. <\/p> <\/li> <li class=\"flauntit product-faq-item\"> <p class=\"flauntit product-faq-item-q\"> <img decoding=\"async\" src=\"\/shop\/dropdown.svg\"\/> \u00bfCu\u00e1nto tiempo tarda la entrega? <\/p> <p class=\"flauntit product-faq-item-a\"> El plazo de entrega depende de la regi\u00f3n y del m\u00e9todo de env\u00edo. Por lo general, la entrega tarda de 2 a 7 d\u00edas. El plazo exacto se indicar\u00e1 en la confirmaci\u00f3n. <\/p> <\/li> <li class=\"flauntit product-faq-item\"> <p class=\"flauntit product-faq-item-q\"> <img decoding=\"async\" src=\"\/shop\/dropdown.svg\"\/> \u00bfC\u00f3mo saber d\u00f3nde est\u00e1 mi pedido? <\/p> <p class=\"flauntit product-faq-item-a\"> Siempre proporcionamos un n\u00famero de seguimiento. Despu\u00e9s del env\u00edo recibir\u00e1 un c\u00f3digo \u00fanico. Utilice el n\u00famero de seguimiento en el sitio del transportista. <\/p> <\/li> <li class=\"flauntit product-faq-item\"> <p class=\"flauntit product-faq-item-q\"> <img decoding=\"async\" src=\"\/shop\/dropdown.svg\"\/> \u00bfSe puede pedir un producto que no est\u00e1 en stock? <\/p> <p class=\"flauntit product-faq-item-a\"> Lamentablemente, si el producto falta no se puede tramitar el pedido. Est\u00e9 atento a la actualizaci\u00f3n del cat\u00e1logo. <\/p> <\/li> <li class=\"flauntit product-faq-item\"> <p class=\"flauntit product-faq-item-q\"> <img decoding=\"async\" src=\"\/shop\/dropdown.svg\"\/> \u00bfSe debe pagar algo m\u00e1s aparte del producto y el env\u00edo? <\/p> <p class=\"flauntit product-faq-item-a\"> No existen comisiones ni cargos extra. No hay cargos ocultos. <\/p> <\/li> <li class=\"flauntit product-faq-item\"> <p class=\"flauntit product-faq-item-q\"> <img decoding=\"async\" src=\"\/shop\/dropdown.svg\"\/> \u00bfCada cu\u00e1nto se a\u00f1aden novedades? <\/p> <p class=\"flauntit product-faq-item-a\"> El cat\u00e1logo se renueva cada semana. Revise las actualizaciones en flauntit.eu. <\/p> <\/li> <\/ul> <\/div><div class=\"flauntit product-action\">    <a href=\"#speaker\" class=\"fancybox product-action-button\" target=\"_self\" aria-controls=\"fancybox-wrap\" aria-haspopup=\"dialog\">Comprar en l\u00ednea Alvioten psoriasis<\/a><\/div><div class=\"flauntit cookies\" style=\"display:none;\">    <div class=\"flauntit cookies-wrap\">        <div class=\"flauntit cookies-text\">We use cookies to improve your experience on the flauntit.eu. By continuing to use the flauntit.eu, you agree to this.<\/div>        <div class=\"flauntit cookies-buttons\">            <button class=\"flauntit cookies-button\" data-c=\"2\">Accept<\/button>            <button class=\"flauntit cookies-button\" data-c=\"1\">Reject<\/button>        <\/div>    <\/div><\/div><div style=\"display: none;\">    <div id=\"speaker\">        <div class=\"speaker-main\"><span>Formulario de reserva<\/span>            <form id=\"orderly\" class=\"landkonsult\" action=\"\/shop\/lemon.php\" method=\"POST\">                <input name=\"name\" required=\"\" type=\"text\" placeholder=\"Su nombre\">                <input name=\"phone\" required=\"\" type=\"number\" placeholder=\"+51\">                <input type=\"hidden\" name=\"offer_id\" value=\"57a87373-767b-4b83-9854-e1ee64fd5a54\"\/>                <input type=\"hidden\" name=\"stream\" value=\"57a87373-767b-4b83-9854-e1ee64fd5a54\"\/>                <input type=\"hidden\" name=\"country\" value=\"PE\"\/>                <button class=\"btn-clculul\" type=\"submit\">Hacer un pedido<\/button>            <\/form>        <\/div>        <div class=\"text-konfigure\"><span class=\"txt-konfid\">Especialista entrar\u00e1 en contacto con usted durante el d\u00eda laborable, dentro de 10\u201315 minutos.<\/span><\/div>    <\/div><\/div>","protected":false},"excerpt":{"rendered":"4.8 \/ 5 T\u00edtulo del producto Alvioten psoriasis Direcci\u00f3n de salud Psoriasis N\u00famero de producto 8420257 Cantidad disponible 324 149 PEN-20% 186.25 PEN El art\u00edculo est\u00e1 certificado. Antes de tomar el suplemento conviene hablar con un m\u00e9dico. Se puede pagar: Se puede pagar en efectivo o con tarjeta al recibir. Sin pago anticipado. Entrega en [&hellip;]","protected":false},"author":1,"featured_media":977,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27],"tags":[],"class_list":["post-978","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-peru"],"_links":{"self":[{"href":"https:\/\/flauntit.eu\/shop\/wp-json\/wp\/v2\/posts\/978","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/flauntit.eu\/shop\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/flauntit.eu\/shop\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/flauntit.eu\/shop\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/flauntit.eu\/shop\/wp-json\/wp\/v2\/comments?post=978"}],"version-history":[{"count":0,"href":"https:\/\/flauntit.eu\/shop\/wp-json\/wp\/v2\/posts\/978\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/flauntit.eu\/shop\/wp-json\/wp\/v2\/media\/977"}],"wp:attachment":[{"href":"https:\/\/flauntit.eu\/shop\/wp-json\/wp\/v2\/media?parent=978"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/flauntit.eu\/shop\/wp-json\/wp\/v2\/categories?post=978"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/flauntit.eu\/shop\/wp-json\/wp\/v2\/tags?post=978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}